{"id":489,"date":"2012-05-05T15:15:06","date_gmt":"2012-05-05T13:15:06","guid":{"rendered":"http:\/\/blogg.improveme.se\/carinapernilla\/?p=489"},"modified":"2012-05-05T18:08:44","modified_gmt":"2012-05-05T16:08:44","slug":"pernilla-carina-attackerar","status":"publish","type":"post","link":"https:\/\/blogg.improveme.se\/carinapernilla\/2012\/05\/05\/pernilla-carina-attackerar\/","title":{"rendered":"Pernilla &amp; carina attackerar!"},"content":{"rendered":"<p>Attack!<a href=\"http:\/\/blogg.improveme.se\/carinapernilla\/files\/2012\/05\/20120505-180826.jpg\"><img decoding=\"async\" src=\"http:\/\/blogg.improveme.se\/carinapernilla\/files\/2012\/05\/20120505-180826.jpg\" alt=\"20120505-180826.jpg\" class=\"alignnone size-full\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attack!<\/p>\n","protected":false},"author":2243,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-489","post","type-post","status-publish","format-standard","hentry","category-carina-pernilla"],"_links":{"self":[{"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/posts\/489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/users\/2243"}],"replies":[{"embeddable":true,"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/comments?post=489"}],"version-history":[{"count":0,"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/posts\/489\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/media?parent=489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/categories?post=489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogg.improveme.se\/carinapernilla\/wp-json\/wp\/v2\/tags?post=489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}